{"id":1796,"date":"2023-03-16T23:48:59","date_gmt":"2023-03-16T23:48:04","guid":{"rendered":"https:\/\/wellspring.ca\/nouveaubrunswick-brampton\/?page_id=1796"},"modified":"2026-07-30T12:33:24","modified_gmt":"2026-07-30T19:33:24","slug":"faq","status":"publish","type":"page","link":"https:\/\/wellspring.ca\/nouveaubrunswick\/programmes\/faq\/","title":{"rendered":"FAQ"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1796\" class=\"elementor elementor-1796\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e34614f elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom elementor-section-height-default\" data-id=\"e34614f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f02f247\" data-id=\"f02f247\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffa877d elementor-widget elementor-widget-heading\" data-id=\"ffa877d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">FAQ<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7fbdfbb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7fbdfbb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26efd89\" data-id=\"26efd89\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-caf7ab2 elementor-widget__width-initial elementor-widget elementor-widget-spacer\" data-id=\"caf7ab2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cfa3d0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cfa3d0b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81b16e2\" data-id=\"81b16e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44d09c1 elementor-widget elementor-widget-jet-breadcrumbs\" data-id=\"44d09c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-breadcrumbs jet-blocks\">\n\t\t<div class=\"jet-breadcrumbs\">\n\t\t<div class=\"jet-breadcrumbs__content\">\n\t\t<div class=\"jet-breadcrumbs__wrap\"><div class=\"jet-breadcrumbs__item\"><a href=\"https:\/\/wellspring.ca\/nouveaubrunswick\/\" class=\"jet-breadcrumbs__item-link is-home\" rel=\"home\" title=\"Accueil\">Accueil<\/a><\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76395b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76395b2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c778f0b\" data-id=\"c778f0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-438707e elementor-widget elementor-widget-heading\" data-id=\"438707e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00c0 propos de Wellspring Nouveau-Brunswick<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-4bddd19\" data-id=\"4bddd19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9da0692 elementor-widget elementor-widget-jet-accordion\" data-id=\"9da0692\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingTablet&quot;:false,&quot;switchScrollingMobile&quot;:false,&quot;switchScrollingOffset&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetTablet&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetMobile&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingDelay&quot;:500,&quot;switchScrollingDelayTablet&quot;:500,&quot;switchScrollingDelayMobile&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1651\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1651\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Qu\u2019est-ce que Wellspring et qui d\u2019autre fera partie des programmes de soutien face au cancer?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1651\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>\u00c0 Wellspring, vous trouverez une gamme de programmes sp\u00e9cialis\u00e9s destin\u00e9 aux personnes atteintes d&rsquo;un cancer et \u00e0 leurs aidants con\u00e7us, pour tisser des liens et cr\u00e9er un sentiment d\u2019appartenance ; soulager la douleur, la fatigue et la d\u00e9tresse ; am\u00e9liorer la force et la mobilit\u00e9 ; et aider \u00e0 faire face aux d\u00e9fis financiers et professionnels.<\/p><p>Les programmes de Wellspring sont tous propos\u00e9s gratuitement et ne n\u00e9cessitent pas de recommandation.<\/p><p>Wellspring Nouveau-Brunswick (NB) est la premi\u00e8re filiale de Wellspring dans le Canada atlantique et est fi\u00e8re de recevoir le soutien de la Fondation des Amis de L\u2019H\u00f4pital de Moncton et de la Fondation CHU Dumont.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1652\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"2\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1652\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Qu'est-ce que la Maison Bannon?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1652\" class=\"jet-toggle__content\" data-toggle=\"2\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>La Maison Bannon, situ\u00e9 \u00e0 166 avenue MacBeath, Moncton, N.-B., est une maison situ\u00e9e pr\u00e8s de L\u2019H\u00f4pital de Moncton dont on a g\u00e9n\u00e9reusement fait don \u00e0 la Fondation. Gr\u00e2ce \u00e0 les incroyables donateurs, la fondation \u00e0 recueilli 1,1 million de dollars pour r\u00e9nover la maison et en faire un centre de ressources pour Wellspring NB et ses membres. Nomm\u00e9 Maison Bannon House en l\u2019honneur de sa bienfaitrice, cet espace a \u00e9t\u00e9 transform\u00e9 en un centre unique pour les patientes et patients atteints de cancer, leur permettant de se rassembler, de tisser des liens avec leurs pairs, de trouver de la force et de participer \u00e0 des programmes favorisant le mieux-\u00eatre.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1653\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"3\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1653\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Les programmes de lutte contre le cancer sont-ils payants pour les participants et leurs soignants?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1653\" class=\"jet-toggle__content\" data-toggle=\"3\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Tous les programmes sont offerts sans frais, et les participants et leurs proches aidants n\u2019ont pas \u00e0 y \u00eatre aguill\u00e9s.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1654\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"4\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1654\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Des collectes de fonds seront-elles organis\u00e9es r\u00e9guli\u00e8rement pour soutenir les programmes de Wellspring NB?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1654\" class=\"jet-toggle__content\" data-toggle=\"4\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Oui, pour que Wellspring demeure un service gratuit pour les personnes atteintes de cancer dans notre communaut\u00e9, nous continuerons de recueillir des fonds pour Wellspring Nouveau\u2011Brunswick dans le cadre d\u2019activit\u00e9s comme Roulons contre le cancer NB.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1655\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"5\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1655\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Wellspring NB dispose-t-il de personnel pour g\u00e9rer et animer les programmes?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1655\" class=\"jet-toggle__content\" data-toggle=\"5\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p><span data-olk-copy-source=\"MessageBody\">Un directeur \u00e0 temps plein sera sur place \u00e0 la Maison Bannon Wellspring pour g\u00e9rer les programmes et les animateurs qui sont des leaders r\u00e9mun\u00e9r\u00e9s et accr\u00e9dit\u00e9s.<\/span><\/p><p>Le comit\u00e9 consultatif des programmes, compos\u00e9 d\u2019oncologues, d\u2019infirmi\u00e8res, de membres du personnel de la Fondation et de personnes ayant une exp\u00e9rience v\u00e9cue, issus des R\u00e9seaux de sant\u00e9 Horizon et Vitalit\u00e9, d\u00e9termineront le contenu des programmes.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55b2dd6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55b2dd6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cd56430\" data-id=\"cd56430\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9ce9bc0 elementor-widget elementor-widget-heading\" data-id=\"9ce9bc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Foire aux questions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-27864ce\" data-id=\"27864ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0829876 elementor-widget elementor-widget-jet-accordion\" data-id=\"0829876\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingTablet&quot;:false,&quot;switchScrollingMobile&quot;:false,&quot;switchScrollingOffset&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetTablet&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetMobile&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingDelay&quot;:500,&quot;switchScrollingDelayTablet&quot;:500,&quot;switchScrollingDelayMobile&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-8551\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-8551\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Pourquoi avons-nous besoin de Wellspring ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-8551\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Le besoin de soutien non m\u00e9dical pour les patients atteints de cancer et leur famille est d\u00e9j\u00e0 bien r\u00e9el&#8230; et ne cesse d&rsquo;augmenter. Au Canada, nous avons la chance de disposer de centres de traitement de classe mondiale, d&rsquo;\u00e9quipes d&rsquo;oncologie sp\u00e9cialis\u00e9es et d&rsquo;excellents fournisseurs de soins auxiliaires. Ceci dit, le syst\u00e8me de sant\u00e9 n&rsquo;a pas les ressources n\u00e9cessaires pour r\u00e9pondre aux importants besoins non m\u00e9dicaux des personnes atteintes de cancer. Wellspring est l\u00e0 pour aider \u00e0 combler cette lacune.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-8552\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"2\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-8552\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Qu'est-ce que Wellspring offre qui n'est pas propos\u00e9 ailleurs ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-8552\" class=\"jet-toggle__content\" data-toggle=\"2\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Les personnes atteintes d&rsquo;un cancer affirment souvent qu&rsquo;elles veulent avoir acc\u00e8s \u00e0 un soutien et \u00e0 des informations quand et o\u00f9 elles en ont besoin. Les centres Wellspring offrent un bien-\u00eatre et un soutien centralis\u00e9s et complets \u00e0 toute personne touch\u00e9e par un cancer, quel qu&rsquo;en soit le type. Plus pr\u00e9cis\u00e9ment, Wellspring fournira un soutien :<\/p><ul><li><p>\u00c0 toute personne touch\u00e9e par le cancer, y compris les membres de la famille, les amis et les proches aidants<\/p><\/li><li>Pour les personnes atteintes de tout type de cancer, \u00e0 tous les stades de la maladie<\/li><li><p>Aussi longtemps que l&rsquo;aide est n\u00e9cessaire<\/p><\/li><li><p>En collaboration avec les traitements m\u00e9dicaux<\/p><\/li><li><p>Dans un cadre familial, non hospitalier et non clinique<\/p><\/li><li><p>Gratuitement et sans rendez-vous<\/p><\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-8553\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"3\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-8553\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Quel est le plus grand atout de Wellspring dans la fourniture de services \u00e0 la communaut\u00e9 ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-8553\" class=\"jet-toggle__content\" data-toggle=\"3\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Le plus grand atout de Wellspring, ce sont ses membres, les patients, les membres de leur famille et les proches aidants qui ont une exp\u00e9rience et des connaissances concr\u00e8tes de la gestion du cancer dans leur propre vie. Lorsque ces personnes se portent volontaires pour aider les autres, elles apportent avec elles une connaissance pratique des moyens de faire face \u00e0 la situation, puis, \u00e9ventuellement, de reprendre le contr\u00f4le de leur vie.<\/p><p>Tr\u00e8s peu d&rsquo;entre nous sont pr\u00e9par\u00e9s \u00e0 entendre les mots \u00ab\u00a0Vous avez un cancer\u00a0\u00bb, et nous nous rendons vite compte que nous en savons tr\u00e8s peu sur la crise \u00e0 laquelle nous sommes confront\u00e9s. \u00c0 Wellspring, les survivants du cancer ont l&rsquo;occasion unique de transmettre leurs connaissances personnelles \u00e0 ceux qui commencent leur parcours.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-8554\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"4\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-8554\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Quelle diff\u00e9rence fait Wellspring ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-8554\" class=\"jet-toggle__content\" data-toggle=\"4\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Un diagnostic de cancer s&rsquo;accompagne souvent de sentiments d&rsquo;incertitude, d&rsquo;impuissance et de peur de l&rsquo;inconnu. La plupart des personnes ont des pr\u00e9occupations tr\u00e8s pratiques, qui vont au-del\u00e0 du traitement m\u00e9dical et des soins. Ils se posent des questions telles que : Que dois-je dire \u00e0 mes enfants ? \u00c0 quoi vais-je ressembler apr\u00e8s l&rsquo;op\u00e9ration ? Quand pourrai-je reprendre le travail ? Comment allons-nous survivre financi\u00e8rement ? Que puis-je faire pour r\u00e9duire le risque de r\u00e9cidive ?<\/p><p>Wellspring est une bou\u00e9e de sauvetage pour ceux qui se trouvent plong\u00e9s dans le chaos par un diagnostic de cancer.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8f064fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f064fc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f7fffd1\" data-id=\"f7fffd1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef85492 elementor-widget elementor-widget-heading\" data-id=\"ef85492\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Acc\u00e9der aux programmes Wellspring<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-e154fff\" data-id=\"e154fff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d8c4d0 elementor-widget elementor-widget-jet-accordion\" data-id=\"8d8c4d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingTablet&quot;:false,&quot;switchScrollingMobile&quot;:false,&quot;switchScrollingOffset&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetTablet&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetMobile&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingDelay&quot;:500,&quot;switchScrollingDelayTablet&quot;:500,&quot;switchScrollingDelayMobile&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1481\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1481\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Comment devenir membre ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1481\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Pour vous inscrire en tant que membre de Wellspring, rendez-vous d&rsquo;abord sur la page d&rsquo;accueil et cliquez sur le bouton \u00ab Rejoignez gratuitement \u00bb, qui vous am\u00e8nera \u00e0 la page \u00ab Commencez ici \u00bb.<\/p><p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-9444 size-large\" title=\"FAQ Images for New Website (6)\" src=\"http:\/\/wellspring.ca\/wp-content\/uploads\/2024\/02\/FAQ-Images-for-New-Website-7-1024x589.png\" alt=\"\" width=\"800\" height=\"460\" \/><\/p><p>A partir de l\u00e0, faites d\u00e9filer vers le bas et cliquez sur l&rsquo;option d&rsquo;adh\u00e9sion appropri\u00e9e. Vous acc\u00e9derez ainsi \u00e0 une page contenant plus de d\u00e9tails sur le type d&rsquo;adh\u00e9sion que vous avez s\u00e9lectionn\u00e9.<\/p><p><img decoding=\"async\" class=\"alignnone wp-image-9445 size-large\" title=\"FAQ Images for New Website (8)\" src=\"http:\/\/wellspring.ca\/wp-content\/uploads\/2024\/02\/FAQ-Images-for-New-Website-8-1024x589.png\" alt=\"\" width=\"800\" height=\"460\" \/><\/p><p>Descendez jusqu&rsquo;\u00e0 la section intitul\u00e9e \u00ab Le processus d&rsquo;inscription\u00a0\u00bb et cliquez sur le bouton \u00ab Inscrivez-vous maintenant\u00a0\u00bb.<\/p><p><img decoding=\"async\" class=\"alignnone wp-image-9482 size-large\" title=\"FAQ Images for New Website (16)\" src=\"http:\/\/wellspring.ca\/wp-content\/uploads\/2024\/02\/FAQ-Images-for-New-Website-16-1024x589.png\" alt=\"\" width=\"800\" height=\"460\" \/><\/p><p>Vous serez ensuite invit\u00e9 \u00e0 fournir des informations de base sur vous-m\u00eame. Une fois ces \u00e9tapes accomplies, vous \u00eates d\u00e9sormais membre et pouvez vous inscrire \u00e0 l&rsquo;un de nos programmes.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9446 size-large\" title=\"FAQ Images for New Website (10)\" src=\"http:\/\/wellspring.ca\/wp-content\/uploads\/2024\/02\/FAQ-Images-for-New-Website-10-1024x589.png\" alt=\"\" width=\"800\" height=\"460\" \/><\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1482\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"2\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1482\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Comment voir les programmes \u00e0 venir ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1482\" class=\"jet-toggle__content\" data-toggle=\"2\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Allez sur <a href=\"https:\/\/portal.wellspring.ca\/\">https:\/\/portal.wellspring.ca\/<\/a> et connectez-vous \u00e0 votre compte de membre.<\/p><p>\u00c0 partir de l\u00e0, vous pouvez faire d\u00e9filer la page ou utiliser les filtres pour trouver le(s) programme(s) qui vous convient(ent).<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9426 size-large\" src=\"http:\/\/wellspring.ca\/wp-content\/uploads\/2024\/02\/FAQ-Images-for-New-Website-3-1024x589.png\" alt=\"\" width=\"800\" height=\"460\" \/><\/p><p>En cliquant sur le nom du programme, vous ouvrirez une page contenant plus d&rsquo;informations sur le programme, notamment l&rsquo;heure \u00e0 laquelle il se d\u00e9roule, le lieu et comment s&rsquo;inscrire.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9427 size-large\" title=\"FAQ Images for New Website (4)\" src=\"http:\/\/wellspring.ca\/wp-content\/uploads\/2024\/02\/FAQ-Images-for-New-Website-4-1024x589.png\" alt=\"FAQ Images for New Website (4)\" width=\"800\" height=\"460\" \/><\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-9428 size-large\" title=\"FAQ Images for New Website (5)\" src=\"http:\/\/wellspring.ca\/wp-content\/uploads\/2024\/02\/FAQ-Images-for-New-Website-5-1024x589.png\" alt=\"FAQ Images for New Website (5)\" width=\"800\" height=\"460\" \/><\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1483\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"3\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1483\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Comment puis-je me connecter au nouveau syst\u00e8me si j'avais un compte dans l'ancien syst\u00e8me ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1483\" class=\"jet-toggle__content\" data-toggle=\"3\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Vous devriez avoir re\u00e7u un courriel de Wellspring le 4 mars, \u00e0 l&rsquo;adresse \u00ab noreply@wellspring.ca\u00a0\u00bb. Cet e-mail contenait un lien vers votre compte. Si vous ne l&rsquo;avez pas encore vu, v\u00e9rifiez votre dossier de courrier ind\u00e9sirable.<\/p><p>Si vous n&rsquo;avez pas re\u00e7u ce courriel, il vous suffit de vous rendre sur le portail du <a href=\"https:\/\/portal.wellspring.ca\/\" target=\"_blank\" rel=\"noopener\">Programme<\/a>, de cliquer sur Connexion, puis de s\u00e9lectionner le lien <a href=\"https:\/\/portal.wellspring.ca\/ForgotPassword\" target=\"_blank\" rel=\"noopener\">Mot de passe oubli\u00e9 ?<\/a>. Vous serez alors invit\u00e9 \u00e0 suivre les \u00e9tapes pour r\u00e9initialiser votre mot de passe.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9447 size-large\" title=\"forgot password\" src=\"http:\/\/wellspring.ca\/wp-content\/uploads\/2024\/02\/FAQ-Images-for-New-Website-11-1024x589.png\" alt=\"\" width=\"800\" height=\"460\" \/><\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1484\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"4\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1484\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Dois-je me connecter pour consulter les programmes ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1484\" class=\"jet-toggle__content\" data-toggle=\"4\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Vous n&rsquo;avez pas besoin de vous connecter pour voir quels sont les programmes disponibles. Toutefois, si vous souhaitez vous inscrire \u00e0 un programme ou consulter votre profil, vous devrez vous connecter.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1485\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"5\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1485\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Comment mettre \u00e0 jour mon profil de membre ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1485\" class=\"jet-toggle__content\" data-toggle=\"5\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Lorsque vous \u00eates connect\u00e9, vous devriez voir l&rsquo;option \u00ab\u00a0Mon profil\u00a0\u00bb dans la barre violette.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9452 size-large\" title=\"FAQ Images for New Website (12)\" src=\"http:\/\/wellspring.ca\/wp-content\/uploads\/2024\/02\/FAQ-Images-for-New-Website-12-1024x589.png\" alt=\"\" width=\"800\" height=\"460\" \/><\/p><p>Une fois dans cet espace, vous pouvez ajouter ou modifier n&rsquo;importe quelle information.<\/p><p>N&rsquo;oubliez pas de cliquer sur \u00ab Sauvegarder\u00a0\u00bb en bas de l&rsquo;\u00e9cran pour enregistrer vos modifications.<\/p><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9453 size-large\" title=\"FAQ Images for New Website (13)\" src=\"http:\/\/wellspring.ca\/wp-content\/uploads\/2024\/02\/FAQ-Images-for-New-Website-13-1024x589.png\" alt=\"\" width=\"800\" height=\"460\" \/><\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1486\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"6\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1486\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Mon conjoint et moi partageons le m\u00eame courriel, pouvons-nous tous deux nous inscrire en tant que membres ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1486\" class=\"jet-toggle__content\" data-toggle=\"6\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Oui, vous pouvez demander \u00e0 votre conjoint de cr\u00e9er son propre compte \u00e0 l&rsquo;aide de la m\u00eame adresse \u00e9lectronique en ajoutant un +1 lors de l&rsquo;inscription. Par exemple :<\/p><p>Le compte de John Doe se trouve \u00e0 l&rsquo;adresse thedoes@gmail.com. Sa femme Jane utilise la m\u00eame adresse \u00e9lectronique. Elle peut cr\u00e9er son propre compte avec son propre mot de passe en s&rsquo;inscrivant en tant que thedoes+1@gmail.com, et elle pourra toujours recevoir les mises \u00e0 jour du programme, les bulletins d&rsquo;information, etc. sur son adresse \u00e9lectronique commune.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1487\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"7\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1487\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Je suis int\u00e9ress\u00e9(e) par un programme qui est complet, que puis-je faire ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1487\" class=\"jet-toggle__content\" data-toggle=\"7\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Si le programme qui vous int\u00e9resse est actuellement complet, vous pouvez vous inscrire sur une liste d&rsquo;attente afin d&rsquo;\u00eatre averti d\u00e8s qu&rsquo;une place se lib\u00e8re. La proc\u00e9dure est la m\u00eame que pour l&rsquo;inscription \u00e0 un programme &#8211; il vous suffit de cliquer sur le bouton <em>Liste d&rsquo;attente<\/em> au lieu du bouton d&rsquo;inscription habituel.<\/p><p>D\u00e8s qu&rsquo;une place se lib\u00e8re dans le programme, vous recevrez un courriel vous informant que vous avez \u00e9t\u00e9 admis. Il se peut \u00e9galement qu&rsquo;un b\u00e9n\u00e9vole de Wellspring vous appelle pour vous informer du changement.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-1488\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"8\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-1488\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Comment utiliser Zoom pour les programmes en ligne ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-1488\" class=\"jet-toggle__content\" data-toggle=\"8\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Zoom est une plateforme de vid\u00e9oconf\u00e9rence utilis\u00e9e pour tous les programmes en ligne de Wellspring.<\/p><p>Tout ce dont vous avez besoin, c&rsquo;est d&rsquo;un ordinateur \u00e9quip\u00e9 d&rsquo;une cam\u00e9ra et d&rsquo;un syst\u00e8me audio.<\/p><p>Vous pouvez utiliser un ordinateur portable, un ordinateur de bureau ou une tablette. Nous vous d\u00e9conseillons d&rsquo;utiliser votre smartphone, car vous risquez d&rsquo;avoir du mal \u00e0 voir l&rsquo;animateur, les autres participants et le mat\u00e9riel en raison de la petite taille de l&rsquo;\u00e9cran.<\/p><p>La premi\u00e8re fois que vous utilisez Zoom :<\/p><ol><li>Vous devez t\u00e9l\u00e9charger Zoom sur votre ordinateur. C&rsquo;est un t\u00e9l\u00e9chargement tr\u00e8s rapide et facile. <a href=\"http:\/\/zoom.us\/\">Visitez http:\/\/zoom.us<\/a><\/li><li>Alternativement, apr\u00e8s vous \u00eatre inscrit(e) \u00e0 un programme en ligne, vous recevrez un courriel automatique de Wellspring qui vous fournira le lien vers la visioconf\u00e9rence \u00e0 laquelle vous vous \u00eates inscrit(e).<br \/><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9480 size-large\" title=\"Capture 2\" src=\"http:\/\/wellspring.ca\/wp-content\/uploads\/2024\/02\/FAQ-Images-for-New-Website-15-1024x589.png\" alt=\"\" width=\"800\" height=\"460\" \/><\/p><\/li><li><p>S\u00e9lectionnez le lien hypertexte dans le corps de l&rsquo;e-mail (comme indiqu\u00e9 dans le cercle) pour rejoindre la r\u00e9union.<\/p><\/li><li><p>La premi\u00e8re fois que vous utiliserez Zoom, le lien vous conduira \u00e0 la page web de Zoom. Une barre contextuelle appara\u00eet en bas de la page. Cliquez sur Ex\u00e9cuter.<\/p><\/li><li>Zoom se t\u00e9l\u00e9chargera rapidement et vous serez int\u00e9gr\u00e9(e) \u00e0 la session du programme. Vous vous verrez sur la vid\u00e9o.<\/li><li><p>Fonctionnalit\u00e9s de Zoom :<\/p><p><strong>Audio :<\/strong> Cliquez sur Rejoindre l&rsquo;audio (situ\u00e9 dans le coin inf\u00e9rieur gauche de l&rsquo;\u00e9cran).<\/p><p><strong>Muet:<\/strong> Cliquez sur ce bouton pour couper ou r\u00e9tablir le son de votre propre audio.<\/p><p><strong>Vid\u00e9o<\/strong>: Cliquez sur ce lien pour vous permettre d&rsquo;\u00eatre vu(e).<\/p><p><strong>Chat:<\/strong> Cliquez sur ce bouton pour envoyer un message \u00e0 l&rsquo;ensemble du groupe ou pour parler en priv\u00e9 avec le responsable du groupe.<\/p><p><strong>Vue galerie :<\/strong> Cliquez sur ce bouton pour donner \u00e0 chaque personne un espace \u00e9gal sur l&rsquo;\u00e9cran. Lorsque l&rsquo;orateur parle, le cadre qui l&rsquo;entoure est mis en \u00e9vidence. La vue de l&rsquo;orateur donne le plus d&rsquo;espace visuel \u00e0 la personne qui parle, tandis que les personnes qui ne parlent pas restent visibles dans de petites cases sur le c\u00f4t\u00e9 droit de l&rsquo;\u00e9cran.<\/p><p><strong>Quitter la r\u00e9union : <\/strong>Cliquez sur ce bouton \u00e0 la fin de la session. Il vous sera demand\u00e9 de confirmer votre intention de quitter la r\u00e9union.<\/p><\/li><\/ol><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3bf96f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bf96f1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2a90b45\" data-id=\"2a90b45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93eb1b0 elementor-widget elementor-widget-heading\" data-id=\"93eb1b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Soutenir Wellspring<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-44b969f\" data-id=\"44b969f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59f2b71 elementor-widget elementor-widget-jet-accordion\" data-id=\"59f2b71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jet-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"jet-accordion\" data-settings=\"{&quot;collapsible&quot;:false,&quot;ajaxTemplate&quot;:false,&quot;switchScrolling&quot;:false,&quot;switchScrollingTablet&quot;:false,&quot;switchScrollingMobile&quot;:false,&quot;switchScrollingOffset&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetTablet&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingOffsetMobile&quot;:{&quot;size&quot;:0,&quot;unit&quot;:&quot;px&quot;},&quot;switchScrollingDelay&quot;:500,&quot;switchScrollingDelayTablet&quot;:500,&quot;switchScrollingDelayMobile&quot;:500}\">\n\t\t\t<div class=\"jet-accordion__inner\">\n\t\t\t\t<div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-9431\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"1\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-9431\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Pourquoi devrais-je faire un don \u00e0 Wellspring ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-9431\" class=\"jet-toggle__content\" data-toggle=\"1\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Wellspring est un groupe d&rsquo;organisations caritatives qui d\u00e9pendent enti\u00e8rement des dons de personnes g\u00e9n\u00e9reuses, de sponsors et d&rsquo;entreprises pour soutenir ses programmes et ses services. Wellspring ne re\u00e7oit aucun financement de base de la part des gouvernements ou des h\u00f4pitaux.<\/p><p>Votre g\u00e9n\u00e9rosit\u00e9 ouvre des portes et am\u00e9liore la vie de ceux qui vivent avec le cancer, en assurant que :<\/p><ul><li>Les personnes atteintes d&rsquo;un cancer continuent de b\u00e9n\u00e9ficier d&rsquo;un large \u00e9ventail de programmes visant \u00e0 r\u00e9pondre \u00e0 leurs besoins \u00e9motionnels, pratiques et physiques essentiels.<\/li><li>Il est possible de r\u00e9pondre \u00e0 la croissance constante du nombre de membres et \u00e0 l&rsquo;\u00e9volution de leurs besoins en mati\u00e8re de soins de soutien aux personnes atteintes d&rsquo;un cancer.<\/li><li>De nouveaux programmes peuvent \u00eatre d\u00e9velopp\u00e9s pour combler les lacunes actuelles dans les soins aux patients atteints de cancer.<\/li><\/ul><p><a href=\"https:\/\/wellspring.ca\/fr\/facons-de-donner\/\">En savoir plus sur les dons \u00e0 Wellspring<\/a><\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-9432\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"2\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-9432\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Recevrai-je un re\u00e7u fiscal pour mon don \u00e0 Wellspring ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-9432\" class=\"jet-toggle__content\" data-toggle=\"2\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Oui, chaque centre Wellspring est une organisation caritative enregistr\u00e9e et fournit des re\u00e7us fiscaux \u00e0 ses donateurs. Tous les donateurs en ligne recevront leur re\u00e7u fiscal rapidement \u00e0 leur adresse \u00e9lectronique apr\u00e8s avoir effectu\u00e9 leur don, et les donateurs hors ligne recevront leur re\u00e7u fiscal par la poste apr\u00e8s que leur don aura \u00e9t\u00e9 trait\u00e9.<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div><div class=\" jet-accordion__item jet-toggle jet-toggle-move-up-effect \">\n\t\t\t\t\t\t\t<div id=\"jet-toggle-control-9433\" class=\"jet-toggle__control elementor-menu-anchor\" data-toggle=\"3\" role=\"button\" tabindex=\"0\" aria-controls=\"jet-toggle-content-9433\" aria-expanded=\"false\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__label-icon jet-toggle-icon-position-right\"><span class=\"jet-toggle__icon icon-normal jet-tabs-icon\"><i class=\"fas fa-plus\"><\/i><\/span><span class=\"jet-toggle__icon icon-active jet-tabs-icon\"><i class=\"fas fa-minus\"><\/i><\/span><\/div><div class=\"jet-toggle__label-text\">Puis-je devenir b\u00e9n\u00e9vole \u00e0 Wellspring ?<\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"jet-toggle-content-9433\" class=\"jet-toggle__content\" data-toggle=\"3\" role=\"region\" data-template-id=\"false\">\n\t\t\t\t\t\t\t\t<div class=\"jet-toggle__content-inner\"><p>Oui !<\/p><p>Les b\u00e9n\u00e9voles sont au c\u0153ur de Wellspring, apportant un soutien important \u00e0 tous les niveaux de l&rsquo;organisation.<\/p><p>Que vous ayez v\u00e9cu votre propre exp\u00e9rience du cancer, que vous ayez \u00e9t\u00e9 l&rsquo;aidant d&rsquo;une personne atteinte de cancer ou que vous ayez des qualit\u00e9s et des comp\u00e9tences \u00e0 partager, Wellspring accueille et appr\u00e9cie votre contribution.<\/p><p><a href=\"https:\/\/wellspring.ca\/fr\/facons-de-donner\/benevolat\/\">En savoir plus sur le b\u00e9n\u00e9volat \u00e0 Wellspring <\/a><\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Accueil \u00c0 propos de Wellspring Nouveau-Brunswick Qu\u2019est-ce que Wellspring et qui d\u2019autre fera partie des programmes de soutien face au cancer? \u00c0 Wellspring, vous trouverez une gamme de programmes sp\u00e9cialis\u00e9s destin\u00e9 aux personnes atteintes d&rsquo;un cancer et \u00e0 leurs aidants con\u00e7us, pour tisser des liens et cr\u00e9er un sentiment d\u2019appartenance ; soulager la douleur, la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":33,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1796","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FAQ - Wellspring Nouveau-Brunswick<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wellspring.ca\/nouveaubrunswick\/programmes\/faq\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FAQ - Wellspring Nouveau-Brunswick\" \/>\n<meta property=\"og:description\" content=\"Accueil \u00c0 propos de Wellspring Nouveau-Brunswick Qu\u2019est-ce que Wellspring et qui d\u2019autre fera partie des programmes de soutien face au cancer? \u00c0 Wellspring, vous trouverez une gamme de programmes sp\u00e9cialis\u00e9s destin\u00e9 aux personnes atteintes d&rsquo;un cancer et \u00e0 leurs aidants con\u00e7us, pour tisser des liens et cr\u00e9er un sentiment d\u2019appartenance ; soulager la douleur, la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wellspring.ca\/nouveaubrunswick\/programmes\/faq\/\" \/>\n<meta property=\"og:site_name\" content=\"Wellspring Nouveau-Brunswick\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-30T19:33:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wellspring.ca\/nouveaubrunswick\/wp-content\/uploads\/sites\/30\/2024\/02\/cropped-favicon_well.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/programmes\\\/faq\\\/\",\"url\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/programmes\\\/faq\\\/\",\"name\":\"FAQ - Wellspring Nouveau-Brunswick\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/programmes\\\/faq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/programmes\\\/faq\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/wellspring.ca\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/FAQ-Images-for-New-Website-7-1024x589.png\",\"datePublished\":\"2023-03-16T23:48:04+00:00\",\"dateModified\":\"2026-07-30T19:33:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/programmes\\\/faq\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/programmes\\\/faq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/programmes\\\/faq\\\/#primaryimage\",\"url\":\"http:\\\/\\\/wellspring.ca\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/FAQ-Images-for-New-Website-7-1024x589.png\",\"contentUrl\":\"http:\\\/\\\/wellspring.ca\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/FAQ-Images-for-New-Website-7-1024x589.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/programmes\\\/faq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programmes\",\"item\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/programmes\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FAQ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/#website\",\"url\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/\",\"name\":\"Wellspring Nouveau-Brunswick\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/#organization\",\"name\":\"Wellspring Nouveau-Brunswick\",\"url\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2023\\\/02\\\/WS_logo_stacked_NB_colours_FR.png\",\"contentUrl\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/wp-content\\\/uploads\\\/sites\\\/30\\\/2023\\\/02\\\/WS_logo_stacked_NB_colours_FR.png\",\"width\":660,\"height\":201,\"caption\":\"Wellspring Nouveau-Brunswick\"},\"image\":{\"@id\":\"https:\\\/\\\/wellspring.ca\\\/nouveaubrunswick\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FAQ - Wellspring Nouveau-Brunswick","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wellspring.ca\/nouveaubrunswick\/programmes\/faq\/","og_locale":"fr_CA","og_type":"article","og_title":"FAQ - Wellspring Nouveau-Brunswick","og_description":"Accueil \u00c0 propos de Wellspring Nouveau-Brunswick Qu\u2019est-ce que Wellspring et qui d\u2019autre fera partie des programmes de soutien face au cancer? \u00c0 Wellspring, vous trouverez une gamme de programmes sp\u00e9cialis\u00e9s destin\u00e9 aux personnes atteintes d&rsquo;un cancer et \u00e0 leurs aidants con\u00e7us, pour tisser des liens et cr\u00e9er un sentiment d\u2019appartenance ; soulager la douleur, la [&hellip;]","og_url":"https:\/\/wellspring.ca\/nouveaubrunswick\/programmes\/faq\/","og_site_name":"Wellspring Nouveau-Brunswick","article_modified_time":"2026-07-30T19:33:24+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/wellspring.ca\/nouveaubrunswick\/wp-content\/uploads\/sites\/30\/2024\/02\/cropped-favicon_well.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wellspring.ca\/nouveaubrunswick\/programmes\/faq\/","url":"https:\/\/wellspring.ca\/nouveaubrunswick\/programmes\/faq\/","name":"FAQ - Wellspring Nouveau-Brunswick","isPartOf":{"@id":"https:\/\/wellspring.ca\/nouveaubrunswick\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wellspring.ca\/nouveaubrunswick\/programmes\/faq\/#primaryimage"},"image":{"@id":"https:\/\/wellspring.ca\/nouveaubrunswick\/programmes\/faq\/#primaryimage"},"thumbnailUrl":"http:\/\/wellspring.ca\/wp-content\/uploads\/2024\/02\/FAQ-Images-for-New-Website-7-1024x589.png","datePublished":"2023-03-16T23:48:04+00:00","dateModified":"2026-07-30T19:33:24+00:00","breadcrumb":{"@id":"https:\/\/wellspring.ca\/nouveaubrunswick\/programmes\/faq\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wellspring.ca\/nouveaubrunswick\/programmes\/faq\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/wellspring.ca\/nouveaubrunswick\/programmes\/faq\/#primaryimage","url":"http:\/\/wellspring.ca\/wp-content\/uploads\/2024\/02\/FAQ-Images-for-New-Website-7-1024x589.png","contentUrl":"http:\/\/wellspring.ca\/wp-content\/uploads\/2024\/02\/FAQ-Images-for-New-Website-7-1024x589.png"},{"@type":"BreadcrumbList","@id":"https:\/\/wellspring.ca\/nouveaubrunswick\/programmes\/faq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wellspring.ca\/nouveaubrunswick\/"},{"@type":"ListItem","position":2,"name":"Programmes","item":"https:\/\/wellspring.ca\/nouveaubrunswick\/programmes\/"},{"@type":"ListItem","position":3,"name":"FAQ"}]},{"@type":"WebSite","@id":"https:\/\/wellspring.ca\/nouveaubrunswick\/#website","url":"https:\/\/wellspring.ca\/nouveaubrunswick\/","name":"Wellspring Nouveau-Brunswick","description":"","publisher":{"@id":"https:\/\/wellspring.ca\/nouveaubrunswick\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wellspring.ca\/nouveaubrunswick\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/wellspring.ca\/nouveaubrunswick\/#organization","name":"Wellspring Nouveau-Brunswick","url":"https:\/\/wellspring.ca\/nouveaubrunswick\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/wellspring.ca\/nouveaubrunswick\/#\/schema\/logo\/image\/","url":"https:\/\/wellspring.ca\/nouveaubrunswick\/wp-content\/uploads\/sites\/30\/2023\/02\/WS_logo_stacked_NB_colours_FR.png","contentUrl":"https:\/\/wellspring.ca\/nouveaubrunswick\/wp-content\/uploads\/sites\/30\/2023\/02\/WS_logo_stacked_NB_colours_FR.png","width":660,"height":201,"caption":"Wellspring Nouveau-Brunswick"},"image":{"@id":"https:\/\/wellspring.ca\/nouveaubrunswick\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/wellspring.ca\/nouveaubrunswick\/wp-json\/wp\/v2\/pages\/1796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wellspring.ca\/nouveaubrunswick\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wellspring.ca\/nouveaubrunswick\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wellspring.ca\/nouveaubrunswick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wellspring.ca\/nouveaubrunswick\/wp-json\/wp\/v2\/comments?post=1796"}],"version-history":[{"count":66,"href":"https:\/\/wellspring.ca\/nouveaubrunswick\/wp-json\/wp\/v2\/pages\/1796\/revisions"}],"predecessor-version":[{"id":10688,"href":"https:\/\/wellspring.ca\/nouveaubrunswick\/wp-json\/wp\/v2\/pages\/1796\/revisions\/10688"}],"up":[{"embeddable":true,"href":"https:\/\/wellspring.ca\/nouveaubrunswick\/wp-json\/wp\/v2\/pages\/33"}],"wp:attachment":[{"href":"https:\/\/wellspring.ca\/nouveaubrunswick\/wp-json\/wp\/v2\/media?parent=1796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}